{"id":109689,"date":"2023-07-17T01:37:02","date_gmt":"2023-07-17T06:37:02","guid":{"rendered":"https:\/\/www.quebakan.com\/v15\/?p=109689"},"modified":"2023-07-17T01:37:02","modified_gmt":"2023-07-17T06:37:02","slug":"grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023","status":"publish","type":"post","link":"https:\/\/www.quebakan.com\/v15\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\/","title":{"rendered":"Grupo Mavesa sorprende con los nuevos modelos de Citro\u00ebn y Dongfeng en el AutoShow 2023"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-109690\" src=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/Foto-1-Mejor-Stand.jpg\" alt=\"\" width=\"710\" height=\"400\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><em>Durante el evento de inauguraci\u00f3n, Mavesa fue reconocido con el primer lugar al mejor stand por su imponente infraestructura de 700m2<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Ecuador, julio 2023.-<\/strong> Grupo Mavesa, l\u00edder en la industria automotriz de Ecuador, present\u00f3 los nuevos modelos de Citro\u00ebn y Dongfeng durante el AutoShow 2023. Estos veh\u00edculos destacan por su dise\u00f1o vanguardista, tecnolog\u00eda avanzada, seguridad y confort.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Citro\u00ebn, marca 100% europea, reconocida por su estilo distintivo y su enfoque en la tecnolog\u00eda de punta, presenta el modelo C3 YOU, este veh\u00edculo es una edici\u00f3n especial basada en el nivel de acabado Feel, destaca por su estilo distintivo y su equipamiento exclusivo. Con detalles como llantas de 15 pulgadas, faros LED, asistente de arranque en pendiente, radio digital y una amplia gama de caracter\u00edsticas de confort.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Adem\u00e1s de su est\u00e9tica excepcional, el Citro\u00ebn C3 YOU est\u00e1 equipado con las \u00faltimas innovaciones tecnol\u00f3gicas para sentir conexi\u00f3n y seguridad en cada viaje. Desde su avanzado sistema de infoentretenimiento hasta sus asistentes de conducci\u00f3n inteligentes, hacen de este auto el reflejo de la elegancia y la personalidad, satisfaciendo las necesidades de aquellos que buscan un veh\u00edculo compacto con estilo y tecnolog\u00eda de vanguardia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Por otro lado, Dongfeng, marca considerada como uno de los grupos automotrices m\u00e1s importantes del continente asi\u00e1tico, tambi\u00e9n presenta tres nuevos modelos: E70 PRO, A60 MAX HYBRID y SUV U TOUR.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>E70 PRO<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Es un autom\u00f3vil 100% el\u00e9ctrico que combina un dise\u00f1o elegante y vanguardista con un rendimiento excepcional. Desde su dise\u00f1o aerodin\u00e1mico hasta su avanzado sistema de propulsi\u00f3n el\u00e9ctrica, este veh\u00edculo encarna la innovaci\u00f3n y la sostenibilidad. Con su motor sincr\u00f3nico de alta eficiencia y una autonom\u00eda de 412 km, el E70 Pro ofrece una experiencia de conducci\u00f3n emocionante y libre de emisiones. Adem\u00e1s, este modelo est\u00e1 equipado con caracter\u00edsticas tecnol\u00f3gicas y de seguridad de \u00faltima generaci\u00f3n, brindando una conducci\u00f3n segura y confiable.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>A60 MAX HYBRID<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Es un sed\u00e1n h\u00edbrido autom\u00e1tico que destaca por su dise\u00f1o aerodin\u00e1mico y elegante. Con su motor h\u00edbrido 1.5 turbo, este modelo ofrece un rendimiento excepcional con mayor velocidad, torque y eficiencia en el consumo de combustible. El A60 MAX cuenta con caracter\u00edsticas de seguridad avanzadas, como airbags delanteros y laterales, frenos antibloqueo (ABS) y control de estabilidad (ESC), brindando tranquilidad y protecci\u00f3n a los ocupantes. En cuanto a su interior, este sed\u00e1n h\u00edbrido ofrece comodidad y lujo, con tapicer\u00eda de eco cuero, sistema de infoentretenimiento y una amplia gama de caracter\u00edsticas de conveniencia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>SUV U TOUR<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Combina seguridad, comodidad y tecnolog\u00eda en un veh\u00edculo familiar. Con su sistema de distribuci\u00f3n de v\u00e1lvulas variable (VVT) y su dise\u00f1o aerodin\u00e1mico, este modelo ofrece un rendimiento eficiente y una experiencia de conducci\u00f3n emocionante. Adem\u00e1s, el SUV U TOUR se destaca por su enfoque en la seguridad, con caracter\u00edsticas como zonas de deformaci\u00f3n programada en caso de accidentes, barras de impacto lateral y una c\u00e1mara de grabaci\u00f3n continua para mayor tranquilidad. La comodidad no se queda atr\u00e1s, ya que este modelo cuenta con una insonorizaci\u00f3n de la cabina, el motor y las llantas, brindando un viaje tranquilo y confortable.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Grupo Mavesa contin\u00faa liderando la industria automotriz en Ecuador, ofreciendo veh\u00edculos de alta calidad y tecnolog\u00eda de vanguardia. \u201c<em>Nos esforzamos por brindar a nuestros clientes la mejor experiencia automotriz posible, nuestro equipo est\u00e1 dedicado a ofrecer un excelente servicio al cliente y a asegurar de que encuentren el veh\u00edculo perfecto que se ajuste a sus necesidades y estilo de vida<\/em>\u201d, menciona Jorge Flores, director de veh\u00edculos livianos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Los asistentes podr\u00e1n disfrutar tambi\u00e9n de la presencia de las impresionantes camionetas ZX Auto, reconocidas por su resistencia y capacidad todoterreno. Tambi\u00e9n, se exhibir\u00e1n los lujosos veh\u00edculos franceses de DS Automobiles, que fusionan elegancia y tecnolog\u00eda de vanguardia en cada detalle. Finalmente, Skywell har\u00e1 acto de presencia con su modelo insignia totalmente el\u00e9ctrico.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>MEJOR STAND 2023<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Durante la ceremonia de inauguraci\u00f3n, Grupo Mavesa fue galardonado con el premio al primer lugar como Mejor Stand del AutoShow 2023. El stand cuenta con una impresionante infraestructura de 700m2, ha sido reconocido por su dise\u00f1o innovador y cautivador. Con luces brillantes, pantallas de alta definici\u00f3n y organizado por marca realzando la esencia de cada una de ellas, creando un espacio envolvente y emocionante para los visitantes. Este premio es un testimonio del compromiso de Grupo Mavesa con la excelencia y la creaci\u00f3n de experiencias \u00fanicas en eventos automotrices como el AutoShow.<\/span><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-109691\" src=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/Foto-2-Presentacion-Citroen.jpg\" alt=\"\" width=\"710\" height=\"400\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-109692\" src=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/Foto-3-Presentacion-Dongfeng.jpg\" alt=\"\" width=\"710\" height=\"400\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante el evento de inauguraci\u00f3n, Mavesa fue reconocido con el primer lugar al mejor stand por su imponente infraestructura de 700m2 Ecuador, julio 2023.- Grupo Mavesa, l\u00edder en la industria automotriz de Ecuador, present\u00f3 los nuevos modelos de Citro\u00ebn y Dongfeng durante el AutoShow 2023. Estos veh\u00edculos destacan por su dise\u00f1o vanguardista, tecnolog\u00eda avanzada, seguridad [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":109691,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"buzzeditor_post_format":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-109689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grupo Mavesa sorprende con los nuevos modelos de Citro\u00ebn y Dongfeng en el AutoShow 2023 &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.quebakan.com\/v15\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grupo Mavesa sorprende con los nuevos modelos de Citro\u00ebn y Dongfeng en el AutoShow 2023 &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....\" \/>\n<meta property=\"og:description\" content=\"Durante el evento de inauguraci\u00f3n, Mavesa fue reconocido con el primer lugar al mejor stand por su imponente infraestructura de 700m2 Ecuador, julio 2023.- Grupo Mavesa, l\u00edder en la industria automotriz de Ecuador, present\u00f3 los nuevos modelos de Citro\u00ebn y Dongfeng durante el AutoShow 2023. Estos veh\u00edculos destacan por su dise\u00f1o vanguardista, tecnolog\u00eda avanzada, seguridad [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.quebakan.com\/v15\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/quebakan\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-17T06:37:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/Foto-2-Presentacion-Citroen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"710\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erick Villafuerte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@quebakanec\" \/>\n<meta name=\"twitter:site\" content=\"@quebakanec\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erick Villafuerte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\\\/\"},\"author\":{\"name\":\"Erick Villafuerte\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/person\\\/d90fa9f9cfa81eb8ace9811e5b7b9118\"},\"headline\":\"Grupo Mavesa sorprende con los nuevos modelos de Citro\u00ebn y Dongfeng en el AutoShow 2023\",\"datePublished\":\"2023-07-17T06:37:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\\\/\"},\"wordCount\":805,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Foto-2-Presentacion-Citroen.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\\\/\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\\\/\",\"name\":\"Grupo Mavesa sorprende con los nuevos modelos de Citro\u00ebn y Dongfeng en el AutoShow 2023 &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Foto-2-Presentacion-Citroen.jpg\",\"datePublished\":\"2023-07-17T06:37:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Foto-2-Presentacion-Citroen.jpg\",\"contentUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Foto-2-Presentacion-Citroen.jpg\",\"width\":710,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grupo Mavesa sorprende con los nuevos modelos de Citro\u00ebn y Dongfeng en el AutoShow 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#website\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/\",\"name\":\"QUEBAKAN\",\"description\":\"..\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#organization\",\"name\":\"Quebakan.com\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logoquebakanenero2021.jpg\",\"contentUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logoquebakanenero2021.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Quebakan.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/quebakan\",\"https:\\\/\\\/x.com\\\/quebakanec\",\"http:\\\/\\\/www.instagram.com\\\/quebakan\",\"http:\\\/\\\/www.youtube.com\\\/quebakan1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/person\\\/d90fa9f9cfa81eb8ace9811e5b7b9118\",\"name\":\"Erick Villafuerte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/avatars\\\/4\\\/1731297654-bpfull.png\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/avatars\\\/4\\\/1731297654-bpfull.png\",\"contentUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/avatars\\\/4\\\/1731297654-bpfull.png\",\"caption\":\"Erick Villafuerte\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grupo Mavesa sorprende con los nuevos modelos de Citro\u00ebn y Dongfeng en el AutoShow 2023 &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.quebakan.com\/v15\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\/","og_locale":"es_ES","og_type":"article","og_title":"Grupo Mavesa sorprende con los nuevos modelos de Citro\u00ebn y Dongfeng en el AutoShow 2023 &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","og_description":"Durante el evento de inauguraci\u00f3n, Mavesa fue reconocido con el primer lugar al mejor stand por su imponente infraestructura de 700m2 Ecuador, julio 2023.- Grupo Mavesa, l\u00edder en la industria automotriz de Ecuador, present\u00f3 los nuevos modelos de Citro\u00ebn y Dongfeng durante el AutoShow 2023. Estos veh\u00edculos destacan por su dise\u00f1o vanguardista, tecnolog\u00eda avanzada, seguridad [&hellip;]","og_url":"https:\/\/www.quebakan.com\/v15\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\/","og_site_name":"QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","article_publisher":"http:\/\/www.facebook.com\/quebakan","article_published_time":"2023-07-17T06:37:02+00:00","og_image":[{"width":710,"height":400,"url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/Foto-2-Presentacion-Citroen.jpg","type":"image\/jpeg"}],"author":"Erick Villafuerte","twitter_card":"summary_large_image","twitter_creator":"@quebakanec","twitter_site":"@quebakanec","twitter_misc":{"Escrito por":"Erick Villafuerte","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.quebakan.com\/v15\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\/#article","isPartOf":{"@id":"https:\/\/www.quebakan.com\/v15\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\/"},"author":{"name":"Erick Villafuerte","@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/person\/d90fa9f9cfa81eb8ace9811e5b7b9118"},"headline":"Grupo Mavesa sorprende con los nuevos modelos de Citro\u00ebn y Dongfeng en el AutoShow 2023","datePublished":"2023-07-17T06:37:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.quebakan.com\/v15\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\/"},"wordCount":805,"commentCount":0,"publisher":{"@id":"https:\/\/www.quebakan.com\/v15\/#organization"},"image":{"@id":"https:\/\/www.quebakan.com\/v15\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/Foto-2-Presentacion-Citroen.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.quebakan.com\/v15\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\/","url":"https:\/\/www.quebakan.com\/v15\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\/","name":"Grupo Mavesa sorprende con los nuevos modelos de Citro\u00ebn y Dongfeng en el AutoShow 2023 &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","isPartOf":{"@id":"https:\/\/www.quebakan.com\/v15\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.quebakan.com\/v15\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.quebakan.com\/v15\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/Foto-2-Presentacion-Citroen.jpg","datePublished":"2023-07-17T06:37:02+00:00","breadcrumb":{"@id":"https:\/\/www.quebakan.com\/v15\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.quebakan.com\/v15\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.quebakan.com\/v15\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\/#primaryimage","url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/Foto-2-Presentacion-Citroen.jpg","contentUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/Foto-2-Presentacion-Citroen.jpg","width":710,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.quebakan.com\/v15\/grupo-mavesa-sorprende-con-los-nuevos-modelos-de-citroen-y-dongfeng-en-el-autoshow-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.quebakan.com\/v15\/"},{"@type":"ListItem","position":2,"name":"Grupo Mavesa sorprende con los nuevos modelos de Citro\u00ebn y Dongfeng en el AutoShow 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.quebakan.com\/v15\/#website","url":"https:\/\/www.quebakan.com\/v15\/","name":"QUEBAKAN","description":"..","publisher":{"@id":"https:\/\/www.quebakan.com\/v15\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.quebakan.com\/v15\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.quebakan.com\/v15\/#organization","name":"Quebakan.com","url":"https:\/\/www.quebakan.com\/v15\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/logo\/image\/","url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/logoquebakanenero2021.jpg","contentUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/logoquebakanenero2021.jpg","width":1920,"height":1080,"caption":"Quebakan.com"},"image":{"@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/quebakan","https:\/\/x.com\/quebakanec","http:\/\/www.instagram.com\/quebakan","http:\/\/www.youtube.com\/quebakan1"]},{"@type":"Person","@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/person\/d90fa9f9cfa81eb8ace9811e5b7b9118","name":"Erick Villafuerte","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/avatars\/4\/1731297654-bpfull.png","url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/avatars\/4\/1731297654-bpfull.png","contentUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/avatars\/4\/1731297654-bpfull.png","caption":"Erick Villafuerte"}}]}},"_links":{"self":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts\/109689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/comments?post=109689"}],"version-history":[{"count":1,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts\/109689\/revisions"}],"predecessor-version":[{"id":109693,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts\/109689\/revisions\/109693"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/media\/109691"}],"wp:attachment":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/media?parent=109689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/categories?post=109689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/tags?post=109689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}