{"id":109716,"date":"2023-07-18T00:28:44","date_gmt":"2023-07-18T05:28:44","guid":{"rendered":"https:\/\/www.quebakan.com\/v15\/?p=109716"},"modified":"2023-07-18T00:28:44","modified_gmt":"2023-07-18T05:28:44","slug":"didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones","status":"publish","type":"post","link":"https:\/\/www.quebakan.com\/v15\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\/","title":{"rendered":"DiDi reafirma sus esfuerzos de seguridad hacia usuarios conductores con nuevas funciones"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-109717\" src=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/Foto-seguridad.jpg\" alt=\"\" width=\"700\" height=\"466\" \/><\/p>\n<ul>\n<li style=\"text-align: justify;\"><span style=\"color: #000000;\"><em>LERT es un portal desarrollado para hacer m\u00e1s eficiente el proceso de colaboraci\u00f3n por solicitud oficial de las autoridades ante incidentes de seguridad donde la compa\u00f1\u00eda puede brindar apoyo en la investigaci\u00f3n del caso.<\/em><\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #000000;\"><em>A partir de ahora los usuarios conductores podr\u00e1n conocer el n\u00famero de viajes que han realizado los usuarios pasajeros antes de aceptar la solicitud.<\/em><\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #000000;\"><em>DiDi pone a disposici\u00f3n de los usuarios conductores m\u00e1s de 20 funciones de seguridad al hacer uso de la app.<\/em><\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Quito, julio 2023. <\/strong>DiDi, la aplicaci\u00f3n tecnol\u00f3gica de soluciones de movilidad m\u00e1s grande del mundo, lanza nuevas funciones que llegan a robustecer el esquema de asistencia en seguridad con el que cuenta la aplicaci\u00f3n para proteger a los usuarios conductores que se conectan a la app, apostando por nuevos desarrollos tecnol\u00f3gicos que respondan a las necesidades locales.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">En el pa\u00eds la inseguridad sigue siendo una de las principales preocupaciones de los ecuatorianos;\u00a0 en una encuesta Gallup realizada entre el 11 de julio y el 22 de agosto del 2022 y publicada a principios de este a\u00f1o, se establece que el 64% de los ecuatorianos no se sienten seguros caminando solos por las calles. Adem\u00e1s, seg\u00fan datos de la Polic\u00eda Nacional, las extorsiones y secuestros han aumentado hasta en un 300% respecto al 2022 y los robos de autos en ciertos sectores de Quito, aumentaron un 36%.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">En este marco, DiDi habilita el portal LERT, activo en Ecuador y todos los pa\u00edses de Latinoam\u00e9rica en donde la aplicaci\u00f3n est\u00e1 disponible. Esta herramienta est\u00e1 dise\u00f1ada para volver m\u00e1s eficiente el proceso de colaboraci\u00f3n por solicitud oficial de informaci\u00f3n ante un caso en el que DiDi pueda brindar apoyo en la investigaci\u00f3n y resoluci\u00f3n del mismo. LERT permite que las autoridades hagan sus requerimientos en cualquier momento del d\u00eda a trav\u00e9s de un proceso sencillo de autenticaci\u00f3n; construyendo una comunicaci\u00f3n m\u00e1s activa, transparente y eficiente con el equipo de soporte de la app. As\u00ed, el portal apunta a contribuir positivamente al control de las unidades policiales con el manejo de la informaci\u00f3n en sus procesos de investigaci\u00f3n.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Adem\u00e1s, en los \u00faltimos meses, el equipo de Seguridad de Soporte DiDi se ha encargado de reunirse con las diferentes fiscal\u00edas de la regi\u00f3n para colaborar y capacitar a las autoridades en el manejo y uso del portal, y de c\u00f3mo realizar requerimientos que cumplan con los requisitos legales estipulados.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Por otro lado, ahora los usuarios conductores podr\u00e1n ver el n\u00famero de viajes realizados por el usuario pasajero antes de aceptar la solicitud. De igual forma, tambi\u00e9n se mostrar\u00e1n en la aplicaci\u00f3n todas las paradas que se tengan durante el recorrido, al mismo nivel de detalle que el punto de recogida y destino. Esto, sumado a la calificaci\u00f3n del usuario pasajero que siempre ha sido visible, permite a los usuarios conductores tomar decisiones informadas que los haga sentir m\u00e1s seguros durante los periodos que est\u00e9n conectados a la app.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u201cAunque el 99.9% de las solicitudes de viajes que se realizan conect\u00e1ndose por medio de la aplicaci\u00f3n terminan sin incidentes reportados, es vital desarrollar constantemente herramientas innovadoras y procesos depurados para que, quienes se benefician de conectarse a trav\u00e9s de DiDi lo puedan hacer de forma cada vez m\u00e1s segura\u201d afirm\u00f3 Pablo Lamuraglia, Director de Seguridad para DiDi en Hispanoam\u00e9rica.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">As\u00ed, estos nuevos desarrollos tecnol\u00f3gicos se suman al esquema de seguridad de DiDi que comprende m\u00e1s de 20 funciones de seguridad para los usuarios conductores entre las que destacan: el Bot\u00f3n de Emergencia, monitoreo del viaje en tiempo real que genera una alerta ante desv\u00edos, paradas inusuales o retrasos, alerta de zonas de riesgo que permite a los usuarios conductores alejarse o rechazar el viaje sin penalizaci\u00f3n, bloqueo de zonas identificadas como de riesgo cr\u00edtico, calificaci\u00f3n del pasajero, reconocimiento facial del pasajero y Soporte 24\/7 a trav\u00e9s de la Central de Emergencias.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Por otro lado, la compa\u00f1\u00eda reconoce que muchos de los avances de este ecosistema no ser\u00edan posibles sin las alianzas que se han generado con organismos privados, tales como Patrullas de Seguridad de la empresa G4S. Con esta alianza, usuarios conductores y usuarios pasajeros, tienen acceso al servicio de patrullas de asistencia en sitio en caso de que consideren que se encuentran en una situaci\u00f3n de riesgo o que amerita acompa\u00f1amiento presencial.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u201cLa seguridad es prioritaria en todos los pa\u00edses y ciudades donde DiDi est\u00e1 disponible, por eso nos enfocamos en conocer las necesidades de todos los actores que se conectan a la app y colaborar con las autoridades. Este tipo de desarrollos en materia de asistencia de seguridad disponibles en la aplicaci\u00f3n buscan minimizar los riesgos para la comunidad que se conecta a trav\u00e9s de DiDi, mediante la tecnolog\u00eda\u201d dijo Lamuraglia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">DiDi reafirma su compromiso con la seguridad de todos los actores que se conectan a trav\u00e9s de la aplicaci\u00f3n. Por eso, hace un llamado para que tanto usuarios pasajeros como usuarios conductores se familiaricen y utilicen las funciones de seguridad para prevenir y minimizar riesgos antes, durante y despu\u00e9s de cada viaje.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LERT es un portal desarrollado para hacer m\u00e1s eficiente el proceso de colaboraci\u00f3n por solicitud oficial de las autoridades ante incidentes de seguridad donde la compa\u00f1\u00eda puede brindar apoyo en la investigaci\u00f3n del caso. A partir de ahora los usuarios conductores podr\u00e1n conocer el n\u00famero de viajes que han realizado los usuarios pasajeros antes de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":109717,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"buzzeditor_post_format":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-109716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DiDi reafirma sus esfuerzos de seguridad hacia usuarios conductores con nuevas funciones &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.quebakan.com\/v15\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DiDi reafirma sus esfuerzos de seguridad hacia usuarios conductores con nuevas funciones &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....\" \/>\n<meta property=\"og:description\" content=\"LERT es un portal desarrollado para hacer m\u00e1s eficiente el proceso de colaboraci\u00f3n por solicitud oficial de las autoridades ante incidentes de seguridad donde la compa\u00f1\u00eda puede brindar apoyo en la investigaci\u00f3n del caso. A partir de ahora los usuarios conductores podr\u00e1n conocer el n\u00famero de viajes que han realizado los usuarios pasajeros antes de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.quebakan.com\/v15\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\/\" \/>\n<meta property=\"og:site_name\" content=\"QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/quebakan\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-18T05:28:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/Foto-seguridad.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erick Villafuerte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@quebakanec\" \/>\n<meta name=\"twitter:site\" content=\"@quebakanec\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erick Villafuerte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\\\/\"},\"author\":{\"name\":\"Erick Villafuerte\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/person\\\/d90fa9f9cfa81eb8ace9811e5b7b9118\"},\"headline\":\"DiDi reafirma sus esfuerzos de seguridad hacia usuarios conductores con nuevas funciones\",\"datePublished\":\"2023-07-18T05:28:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\\\/\"},\"wordCount\":898,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Foto-seguridad.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\\\/\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\\\/\",\"name\":\"DiDi reafirma sus esfuerzos de seguridad hacia usuarios conductores con nuevas funciones &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Foto-seguridad.jpg\",\"datePublished\":\"2023-07-18T05:28:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Foto-seguridad.jpg\",\"contentUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Foto-seguridad.jpg\",\"width\":700,\"height\":466},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DiDi reafirma sus esfuerzos de seguridad hacia usuarios conductores con nuevas funciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#website\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/\",\"name\":\"QUEBAKAN\",\"description\":\"..\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#organization\",\"name\":\"Quebakan.com\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logoquebakanenero2021.jpg\",\"contentUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logoquebakanenero2021.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Quebakan.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/quebakan\",\"https:\\\/\\\/x.com\\\/quebakanec\",\"http:\\\/\\\/www.instagram.com\\\/quebakan\",\"http:\\\/\\\/www.youtube.com\\\/quebakan1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/person\\\/d90fa9f9cfa81eb8ace9811e5b7b9118\",\"name\":\"Erick Villafuerte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/avatars\\\/4\\\/1731297654-bpfull.png\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/avatars\\\/4\\\/1731297654-bpfull.png\",\"contentUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/avatars\\\/4\\\/1731297654-bpfull.png\",\"caption\":\"Erick Villafuerte\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DiDi reafirma sus esfuerzos de seguridad hacia usuarios conductores con nuevas funciones &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.quebakan.com\/v15\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\/","og_locale":"es_ES","og_type":"article","og_title":"DiDi reafirma sus esfuerzos de seguridad hacia usuarios conductores con nuevas funciones &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","og_description":"LERT es un portal desarrollado para hacer m\u00e1s eficiente el proceso de colaboraci\u00f3n por solicitud oficial de las autoridades ante incidentes de seguridad donde la compa\u00f1\u00eda puede brindar apoyo en la investigaci\u00f3n del caso. A partir de ahora los usuarios conductores podr\u00e1n conocer el n\u00famero de viajes que han realizado los usuarios pasajeros antes de [&hellip;]","og_url":"https:\/\/www.quebakan.com\/v15\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\/","og_site_name":"QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","article_publisher":"http:\/\/www.facebook.com\/quebakan","article_published_time":"2023-07-18T05:28:44+00:00","og_image":[{"width":700,"height":466,"url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/Foto-seguridad.jpg","type":"image\/jpeg"}],"author":"Erick Villafuerte","twitter_card":"summary_large_image","twitter_creator":"@quebakanec","twitter_site":"@quebakanec","twitter_misc":{"Escrito por":"Erick Villafuerte","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.quebakan.com\/v15\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\/#article","isPartOf":{"@id":"https:\/\/www.quebakan.com\/v15\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\/"},"author":{"name":"Erick Villafuerte","@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/person\/d90fa9f9cfa81eb8ace9811e5b7b9118"},"headline":"DiDi reafirma sus esfuerzos de seguridad hacia usuarios conductores con nuevas funciones","datePublished":"2023-07-18T05:28:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.quebakan.com\/v15\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\/"},"wordCount":898,"commentCount":0,"publisher":{"@id":"https:\/\/www.quebakan.com\/v15\/#organization"},"image":{"@id":"https:\/\/www.quebakan.com\/v15\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\/#primaryimage"},"thumbnailUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/Foto-seguridad.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.quebakan.com\/v15\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\/","url":"https:\/\/www.quebakan.com\/v15\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\/","name":"DiDi reafirma sus esfuerzos de seguridad hacia usuarios conductores con nuevas funciones &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","isPartOf":{"@id":"https:\/\/www.quebakan.com\/v15\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.quebakan.com\/v15\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\/#primaryimage"},"image":{"@id":"https:\/\/www.quebakan.com\/v15\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\/#primaryimage"},"thumbnailUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/Foto-seguridad.jpg","datePublished":"2023-07-18T05:28:44+00:00","breadcrumb":{"@id":"https:\/\/www.quebakan.com\/v15\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.quebakan.com\/v15\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.quebakan.com\/v15\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\/#primaryimage","url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/Foto-seguridad.jpg","contentUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/Foto-seguridad.jpg","width":700,"height":466},{"@type":"BreadcrumbList","@id":"https:\/\/www.quebakan.com\/v15\/didi-reafirma-sus-esfuerzos-de-seguridad-hacia-usuarios-conductores-con-nuevas-funciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.quebakan.com\/v15\/"},{"@type":"ListItem","position":2,"name":"DiDi reafirma sus esfuerzos de seguridad hacia usuarios conductores con nuevas funciones"}]},{"@type":"WebSite","@id":"https:\/\/www.quebakan.com\/v15\/#website","url":"https:\/\/www.quebakan.com\/v15\/","name":"QUEBAKAN","description":"..","publisher":{"@id":"https:\/\/www.quebakan.com\/v15\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.quebakan.com\/v15\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.quebakan.com\/v15\/#organization","name":"Quebakan.com","url":"https:\/\/www.quebakan.com\/v15\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/logo\/image\/","url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/logoquebakanenero2021.jpg","contentUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/logoquebakanenero2021.jpg","width":1920,"height":1080,"caption":"Quebakan.com"},"image":{"@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/quebakan","https:\/\/x.com\/quebakanec","http:\/\/www.instagram.com\/quebakan","http:\/\/www.youtube.com\/quebakan1"]},{"@type":"Person","@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/person\/d90fa9f9cfa81eb8ace9811e5b7b9118","name":"Erick Villafuerte","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/avatars\/4\/1731297654-bpfull.png","url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/avatars\/4\/1731297654-bpfull.png","contentUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/avatars\/4\/1731297654-bpfull.png","caption":"Erick Villafuerte"}}]}},"_links":{"self":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts\/109716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/comments?post=109716"}],"version-history":[{"count":1,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts\/109716\/revisions"}],"predecessor-version":[{"id":109718,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts\/109716\/revisions\/109718"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/media\/109717"}],"wp:attachment":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/media?parent=109716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/categories?post=109716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/tags?post=109716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}