{"id":119148,"date":"2024-05-18T21:47:45","date_gmt":"2024-05-19T02:47:45","guid":{"rendered":"https:\/\/www.quebakan.com\/v15\/?p=119148"},"modified":"2024-05-18T21:47:45","modified_gmt":"2024-05-19T02:47:45","slug":"crece-la-instalacion-de-jardines-polinizadores-en-ecuador","status":"publish","type":"post","link":"https:\/\/www.quebakan.com\/v15\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\/","title":{"rendered":"Crece la instalaci\u00f3n de jardines polinizadores en Ecuador"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-119149\" src=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/05\/1-2.jpg\" alt=\"\" width=\"700\" height=\"525\" \/><\/p>\n<ul>\n<li style=\"text-align: justify;\"><span style=\"color: #000000;\">Seg\u00fan el Instituto Earthwatch y las Naciones Unidas, las abejas han sido declaradas los seres vivos m\u00e1s importantes del planeta.<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #000000;\">La FAO revel\u00f3 que el 90% de las plantas con flores y el 75% de los cultivos alimentarios dependen de la polinizaci\u00f3n<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #000000;\">El 35% de la producci\u00f3n mundial de alimentos depende de los polinizadores.<\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Quito, mayo de 2024. <\/strong>\u00a1La vida depende de la polinizaci\u00f3n! Los polinizadores no solo sostienen los ecosistemas y la estabilidad de los h\u00e1bitats, sino que tambi\u00e9n son fundamentales para la seguridad alimentaria mundial, con un impacto econ\u00f3mico de hasta $577 mil millones de d\u00f3lares anuales seg\u00fan IPBES. Sin embargo, su h\u00e1bitat se ve amenazado por varios factores como la urbanizaci\u00f3n y la degradaci\u00f3n ambiental.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">En un esfuerzo por aportar a la problem\u00e1tica, BASF en colaboraci\u00f3n con la Alcald\u00eda de Daule, ha inaugurado el primer jard\u00edn polinizador BEEMusic en la plazoleta del centro cultural del cant\u00f3n Daule (Guayas). Este hito marca el inicio de una iniciativa que contempla la creaci\u00f3n de varios jardines similares en distintas zonas del pa\u00eds, con el fin de proteger a las abejas y otros polinizadores esenciales.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Leonardo Virviescas, L\u00edder Regional (Latinoam\u00e9rica Pac\u00edfico) de Comunicaciones de Soluciones para la Agricultura en BASF menciona que <em>\u00abEl primer jard\u00edn polinizador instalado, alberga una variedad estrat\u00e9gica de plantas, incluyendo ixoras, girasoles, margaritas, chabelitas y geranios, cuidadosamente seleccionadas para atraer y alimentar a las abejas y dem\u00e1s polinizadores. Adem\u00e1s, se integr\u00f3 un bebedero artificial, dise\u00f1ado para brindar un suministro constante de agua limpia y fresca, esencial para la salud y el bienestar de estos polinizadores.\u201d<\/em> Adicionalmente, a\u00f1adi\u00f3 que esta iniciativa no solo ayuda a su supervivencia, sino que tambi\u00e9n promueve la biodiversidad y la sostenibilidad agr\u00edcola en la comunidad.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Seg\u00fan Virviescas, algunos de los beneficios clave de los jardines polinizadores incluyen:<\/span><\/p>\n<ul style=\"text-align: justify;\">\n<li><span style=\"color: #000000;\">Combatir el efecto de isla de calor.<\/span><\/li>\n<li><span style=\"color: #000000;\">Mejorar la calidad del aire.<\/span><\/li>\n<li><span style=\"color: #000000;\">Contribuir a la biodiversidad urbana y otros numerosos beneficios para el medio ambiente y para los seres humanos.<\/span><\/li>\n<li><span style=\"color: #000000;\">Ayudar a proteger y preservar las especies de polinizadores.<\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Patricio Gan\u00e1n, jefe de cooperaci\u00f3n agr\u00edcola de la Alcald\u00eda de Daule manifiesta que eEste tipo de iniciativas deber\u00edan ser adoptadas por las instituciones p\u00fablicas y privadas como pol\u00edticas para proteger a las abejas y los polinizadores. \u201cEmbellecen el entorno urbano y contribuyen a una iniciativa crucial: atraer y proteger a los insectos polinizadores. Agradezco a BASF por estos jardines, f\u00e1ciles de implementar incluso en nuestros hogares\u201d, concluye.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La implementaci\u00f3n de jardines polinizadores se presenta como una soluci\u00f3n esencial para restaurar los ecosistemas da\u00f1ados y enfrentar el cambio clim\u00e1tico. Estudios, como el publicado en Urban Ecosystems en 2018, respaldan que estos jardines pueden aumentar hasta en un 45% la abundancia y diversidad de polinizadores en \u00e1reas urbanas. Esto subraya su importancia cr\u00edtica para la protecci\u00f3n de las abejas, la seguridad alimentaria y la salud del planeta.<\/span><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-119150\" src=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/05\/2-2.jpg\" alt=\"\" width=\"700\" height=\"468\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-119151\" src=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/05\/3-2.jpg\" alt=\"\" width=\"525\" height=\"700\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan el Instituto Earthwatch y las Naciones Unidas, las abejas han sido declaradas los seres vivos m\u00e1s importantes del planeta. La FAO revel\u00f3 que el 90% de las plantas con flores y el 75% de los cultivos alimentarios dependen de la polinizaci\u00f3n El 35% de la producci\u00f3n mundial de alimentos depende de los polinizadores. Quito, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":119149,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"buzzeditor_post_format":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-119148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Crece la instalaci\u00f3n de jardines polinizadores en Ecuador &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.quebakan.com\/v15\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crece la instalaci\u00f3n de jardines polinizadores en Ecuador &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....\" \/>\n<meta property=\"og:description\" content=\"Seg\u00fan el Instituto Earthwatch y las Naciones Unidas, las abejas han sido declaradas los seres vivos m\u00e1s importantes del planeta. La FAO revel\u00f3 que el 90% de las plantas con flores y el 75% de los cultivos alimentarios dependen de la polinizaci\u00f3n El 35% de la producci\u00f3n mundial de alimentos depende de los polinizadores. Quito, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.quebakan.com\/v15\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\/\" \/>\n<meta property=\"og:site_name\" content=\"QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/quebakan\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-19T02:47:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/05\/1-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erick Villafuerte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@quebakanec\" \/>\n<meta name=\"twitter:site\" content=\"@quebakanec\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erick Villafuerte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\\\/\"},\"author\":{\"name\":\"Erick Villafuerte\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/person\\\/d90fa9f9cfa81eb8ace9811e5b7b9118\"},\"headline\":\"Crece la instalaci\u00f3n de jardines polinizadores en Ecuador\",\"datePublished\":\"2024-05-19T02:47:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\\\/\"},\"wordCount\":517,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/1-2.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\\\/\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\\\/\",\"name\":\"Crece la instalaci\u00f3n de jardines polinizadores en Ecuador &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/1-2.jpg\",\"datePublished\":\"2024-05-19T02:47:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/1-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/1-2.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crece la instalaci\u00f3n de jardines polinizadores en Ecuador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#website\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/\",\"name\":\"QUEBAKAN\",\"description\":\"..\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#organization\",\"name\":\"Quebakan.com\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logoquebakanenero2021.jpg\",\"contentUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logoquebakanenero2021.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Quebakan.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/quebakan\",\"https:\\\/\\\/x.com\\\/quebakanec\",\"http:\\\/\\\/www.instagram.com\\\/quebakan\",\"http:\\\/\\\/www.youtube.com\\\/quebakan1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/person\\\/d90fa9f9cfa81eb8ace9811e5b7b9118\",\"name\":\"Erick Villafuerte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/avatars\\\/4\\\/1731297654-bpfull.png\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/avatars\\\/4\\\/1731297654-bpfull.png\",\"contentUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/avatars\\\/4\\\/1731297654-bpfull.png\",\"caption\":\"Erick Villafuerte\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crece la instalaci\u00f3n de jardines polinizadores en Ecuador &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.quebakan.com\/v15\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\/","og_locale":"es_ES","og_type":"article","og_title":"Crece la instalaci\u00f3n de jardines polinizadores en Ecuador &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","og_description":"Seg\u00fan el Instituto Earthwatch y las Naciones Unidas, las abejas han sido declaradas los seres vivos m\u00e1s importantes del planeta. La FAO revel\u00f3 que el 90% de las plantas con flores y el 75% de los cultivos alimentarios dependen de la polinizaci\u00f3n El 35% de la producci\u00f3n mundial de alimentos depende de los polinizadores. Quito, [&hellip;]","og_url":"https:\/\/www.quebakan.com\/v15\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\/","og_site_name":"QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","article_publisher":"http:\/\/www.facebook.com\/quebakan","article_published_time":"2024-05-19T02:47:45+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/05\/1-2.jpg","type":"image\/jpeg"}],"author":"Erick Villafuerte","twitter_card":"summary_large_image","twitter_creator":"@quebakanec","twitter_site":"@quebakanec","twitter_misc":{"Escrito por":"Erick Villafuerte","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.quebakan.com\/v15\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\/#article","isPartOf":{"@id":"https:\/\/www.quebakan.com\/v15\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\/"},"author":{"name":"Erick Villafuerte","@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/person\/d90fa9f9cfa81eb8ace9811e5b7b9118"},"headline":"Crece la instalaci\u00f3n de jardines polinizadores en Ecuador","datePublished":"2024-05-19T02:47:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.quebakan.com\/v15\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\/"},"wordCount":517,"commentCount":0,"publisher":{"@id":"https:\/\/www.quebakan.com\/v15\/#organization"},"image":{"@id":"https:\/\/www.quebakan.com\/v15\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\/#primaryimage"},"thumbnailUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/05\/1-2.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.quebakan.com\/v15\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\/","url":"https:\/\/www.quebakan.com\/v15\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\/","name":"Crece la instalaci\u00f3n de jardines polinizadores en Ecuador &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","isPartOf":{"@id":"https:\/\/www.quebakan.com\/v15\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.quebakan.com\/v15\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\/#primaryimage"},"image":{"@id":"https:\/\/www.quebakan.com\/v15\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\/#primaryimage"},"thumbnailUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/05\/1-2.jpg","datePublished":"2024-05-19T02:47:45+00:00","breadcrumb":{"@id":"https:\/\/www.quebakan.com\/v15\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.quebakan.com\/v15\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.quebakan.com\/v15\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\/#primaryimage","url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/05\/1-2.jpg","contentUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/05\/1-2.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.quebakan.com\/v15\/crece-la-instalacion-de-jardines-polinizadores-en-ecuador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.quebakan.com\/v15\/"},{"@type":"ListItem","position":2,"name":"Crece la instalaci\u00f3n de jardines polinizadores en Ecuador"}]},{"@type":"WebSite","@id":"https:\/\/www.quebakan.com\/v15\/#website","url":"https:\/\/www.quebakan.com\/v15\/","name":"QUEBAKAN","description":"..","publisher":{"@id":"https:\/\/www.quebakan.com\/v15\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.quebakan.com\/v15\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.quebakan.com\/v15\/#organization","name":"Quebakan.com","url":"https:\/\/www.quebakan.com\/v15\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/logo\/image\/","url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/logoquebakanenero2021.jpg","contentUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/logoquebakanenero2021.jpg","width":1920,"height":1080,"caption":"Quebakan.com"},"image":{"@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/quebakan","https:\/\/x.com\/quebakanec","http:\/\/www.instagram.com\/quebakan","http:\/\/www.youtube.com\/quebakan1"]},{"@type":"Person","@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/person\/d90fa9f9cfa81eb8ace9811e5b7b9118","name":"Erick Villafuerte","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/avatars\/4\/1731297654-bpfull.png","url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/avatars\/4\/1731297654-bpfull.png","contentUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/avatars\/4\/1731297654-bpfull.png","caption":"Erick Villafuerte"}}]}},"_links":{"self":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts\/119148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/comments?post=119148"}],"version-history":[{"count":1,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts\/119148\/revisions"}],"predecessor-version":[{"id":119152,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts\/119148\/revisions\/119152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/media\/119149"}],"wp:attachment":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/media?parent=119148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/categories?post=119148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/tags?post=119148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}