{"id":119159,"date":"2024-05-19T00:17:57","date_gmt":"2024-05-19T05:17:57","guid":{"rendered":"https:\/\/www.quebakan.com\/v15\/?p=119159"},"modified":"2024-05-19T00:17:57","modified_gmt":"2024-05-19T05:17:57","slug":"el-poker-es-el-nuevo-deporte-mental","status":"publish","type":"post","link":"https:\/\/www.quebakan.com\/v15\/el-poker-es-el-nuevo-deporte-mental\/","title":{"rendered":"EL POKER ES EL NUEVO DEPORTE MENTAL"},"content":{"rendered":"<ul>\n<li style=\"text-align: justify;\"><span style=\"color: #000000;\">Desde el 2022, el p\u00f3ker fue declarado como deporte mental a nivel mundial.<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #000000;\">Asopoker realiza su tercer torneo de p\u00f3ker en el Hotel Hilton Col\u00f3n Quito desde el 16 hasta el 19 de mayo.<\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El p\u00f3ker es un deporte mental que implica una serie y combinaci\u00f3n de habilidades cognitivas. A lo largo de los a\u00f1os, ha sido una fuente de entretenimiento, estrategia y de rentabilidad. International Federation of Poker (IFP) ha abogado por el reconocimiento del p\u00f3ker como deporte mental y ha trabajado para establecer est\u00e1ndares y regulaciones. En algunos pa\u00edses, este reconocimiento ha llevado a la inclusi\u00f3n del p\u00f3ker en eventos deportivos y la regulaci\u00f3n gubernamental de su industria. En Ecuador, Asopoker realizar\u00e1 un torneo en el Hotel Hilton Col\u00f3n Quito desde el 16 hasta el 19 de mayo, gracias a que se ingresaron los permisos al Ministerio de Deporte y fue adjudicado como el primer club deportivo informativo de p\u00f3ker con la viabilidad legal que otorga el Ministerio mencionado.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Actualmente, Asopoker es la \u00fanica marca en el pa\u00eds que puede operar el p\u00f3ker en todas sus modalidades. Con la finalidad de promover este deporte, Asopoker, junto con otros organizadores como Ecuadorian Poker Series (EPS) y EcuaPoker, realizan la tercera edici\u00f3n, en la cual se contemplan alrededor de 1500 jugadores e invitados internacionales de Colombia, Panam\u00e1, Brasil, entre otros. Adicional, tienen 30mil GTZ garantizados y el ganador 10mil. En las anteriores ediciones han tenido una excelente acogida y asistencia con jugadores de todo el pa\u00eds.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Entre los beneficios que tendr\u00e1n los participantes y quienes practican este deporte est\u00e1n: la mejora en la toma de decisiones, desarrollo de la paciencia, fortalecimiento de la concentraci\u00f3n y habilidad para gestionar el riesgo. Todo estos se logra debido a que los jugadores desarrollan destrezas para actuar r\u00e1pido, esperar el momento adecuado, mantenerse enfocados durante largos periodos de tiempo, mejorando la atenci\u00f3n y aprenden a evaluar riesgos y recompensas antes de tomar decisiones.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El torneo es abierto para todo el p\u00fablico y se pueden inscribir directamente con Asopoker o en las instalaciones del d\u00eda del evento, cuesta $150 + $20 la entrada, hay un RE Buy de $100 y ADD ON de $100.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Por otro lado, el club tiene como objetivo abrir una escuela de p\u00f3ker en Guayaquil, Quito, Manta y Cuenca, para mayores de 18 a\u00f1os, con inscripciones totalmente gratuitas, impulsando este deporte y estimulando las ventajas del mismo en el pa\u00eds.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La inclusi\u00f3n del p\u00f3ker en eventos deportivos y la regulaci\u00f3n gubernamental de su industria pueden proporcionar beneficios significativos para los jugadores y la comunidad en general. El torneo en el Hotel Hilton Col\u00f3n Quito es una oportunidad para impulsar el reconocimiento del p\u00f3ker como deporte mental en Ecuador.<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-119160\" src=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/05\/765580fb-c8ad-45e6-90e8-7cea841d3d8c.jpg\" alt=\"\" width=\"700\" height=\"394\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-119161\" src=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/05\/64febdcc-7ec8-4baf-a499-ffde7fee9baf.jpg\" alt=\"\" width=\"700\" height=\"394\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-119162\" src=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/05\/693e8124-bb7a-4775-8ef2-fba952c38b05.jpg\" alt=\"\" width=\"700\" height=\"394\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el 2022, el p\u00f3ker fue declarado como deporte mental a nivel mundial. Asopoker realiza su tercer torneo de p\u00f3ker en el Hotel Hilton Col\u00f3n Quito desde el 16 hasta el 19 de mayo. El p\u00f3ker es un deporte mental que implica una serie y combinaci\u00f3n de habilidades cognitivas. A lo largo de los a\u00f1os, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":119161,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"buzzeditor_post_format":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-119159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EL POKER ES EL NUEVO DEPORTE MENTAL &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.quebakan.com\/v15\/el-poker-es-el-nuevo-deporte-mental\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EL POKER ES EL NUEVO DEPORTE MENTAL &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....\" \/>\n<meta property=\"og:description\" content=\"Desde el 2022, el p\u00f3ker fue declarado como deporte mental a nivel mundial. Asopoker realiza su tercer torneo de p\u00f3ker en el Hotel Hilton Col\u00f3n Quito desde el 16 hasta el 19 de mayo. El p\u00f3ker es un deporte mental que implica una serie y combinaci\u00f3n de habilidades cognitivas. A lo largo de los a\u00f1os, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.quebakan.com\/v15\/el-poker-es-el-nuevo-deporte-mental\/\" \/>\n<meta property=\"og:site_name\" content=\"QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/quebakan\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-19T05:17:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/05\/64febdcc-7ec8-4baf-a499-ffde7fee9baf.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erick Villafuerte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@quebakanec\" \/>\n<meta name=\"twitter:site\" content=\"@quebakanec\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erick Villafuerte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/el-poker-es-el-nuevo-deporte-mental\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/el-poker-es-el-nuevo-deporte-mental\\\/\"},\"author\":{\"name\":\"Erick Villafuerte\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/person\\\/d90fa9f9cfa81eb8ace9811e5b7b9118\"},\"headline\":\"EL POKER ES EL NUEVO DEPORTE MENTAL\",\"datePublished\":\"2024-05-19T05:17:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/el-poker-es-el-nuevo-deporte-mental\\\/\"},\"wordCount\":477,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/el-poker-es-el-nuevo-deporte-mental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/64febdcc-7ec8-4baf-a499-ffde7fee9baf.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/el-poker-es-el-nuevo-deporte-mental\\\/\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/el-poker-es-el-nuevo-deporte-mental\\\/\",\"name\":\"EL POKER ES EL NUEVO DEPORTE MENTAL &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/el-poker-es-el-nuevo-deporte-mental\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/el-poker-es-el-nuevo-deporte-mental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/64febdcc-7ec8-4baf-a499-ffde7fee9baf.jpg\",\"datePublished\":\"2024-05-19T05:17:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/el-poker-es-el-nuevo-deporte-mental\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/el-poker-es-el-nuevo-deporte-mental\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/el-poker-es-el-nuevo-deporte-mental\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/64febdcc-7ec8-4baf-a499-ffde7fee9baf.jpg\",\"contentUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/64febdcc-7ec8-4baf-a499-ffde7fee9baf.jpg\",\"width\":700,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/el-poker-es-el-nuevo-deporte-mental\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EL POKER ES EL NUEVO DEPORTE MENTAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#website\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/\",\"name\":\"QUEBAKAN\",\"description\":\"..\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#organization\",\"name\":\"Quebakan.com\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logoquebakanenero2021.jpg\",\"contentUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logoquebakanenero2021.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Quebakan.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/quebakan\",\"https:\\\/\\\/x.com\\\/quebakanec\",\"http:\\\/\\\/www.instagram.com\\\/quebakan\",\"http:\\\/\\\/www.youtube.com\\\/quebakan1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/person\\\/d90fa9f9cfa81eb8ace9811e5b7b9118\",\"name\":\"Erick Villafuerte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/avatars\\\/4\\\/1731297654-bpfull.png\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/avatars\\\/4\\\/1731297654-bpfull.png\",\"contentUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/avatars\\\/4\\\/1731297654-bpfull.png\",\"caption\":\"Erick Villafuerte\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EL POKER ES EL NUEVO DEPORTE MENTAL &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.quebakan.com\/v15\/el-poker-es-el-nuevo-deporte-mental\/","og_locale":"es_ES","og_type":"article","og_title":"EL POKER ES EL NUEVO DEPORTE MENTAL &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","og_description":"Desde el 2022, el p\u00f3ker fue declarado como deporte mental a nivel mundial. Asopoker realiza su tercer torneo de p\u00f3ker en el Hotel Hilton Col\u00f3n Quito desde el 16 hasta el 19 de mayo. El p\u00f3ker es un deporte mental que implica una serie y combinaci\u00f3n de habilidades cognitivas. A lo largo de los a\u00f1os, [&hellip;]","og_url":"https:\/\/www.quebakan.com\/v15\/el-poker-es-el-nuevo-deporte-mental\/","og_site_name":"QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","article_publisher":"http:\/\/www.facebook.com\/quebakan","article_published_time":"2024-05-19T05:17:57+00:00","og_image":[{"width":700,"height":394,"url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/05\/64febdcc-7ec8-4baf-a499-ffde7fee9baf.jpg","type":"image\/jpeg"}],"author":"Erick Villafuerte","twitter_card":"summary_large_image","twitter_creator":"@quebakanec","twitter_site":"@quebakanec","twitter_misc":{"Escrito por":"Erick Villafuerte","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.quebakan.com\/v15\/el-poker-es-el-nuevo-deporte-mental\/#article","isPartOf":{"@id":"https:\/\/www.quebakan.com\/v15\/el-poker-es-el-nuevo-deporte-mental\/"},"author":{"name":"Erick Villafuerte","@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/person\/d90fa9f9cfa81eb8ace9811e5b7b9118"},"headline":"EL POKER ES EL NUEVO DEPORTE MENTAL","datePublished":"2024-05-19T05:17:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.quebakan.com\/v15\/el-poker-es-el-nuevo-deporte-mental\/"},"wordCount":477,"commentCount":0,"publisher":{"@id":"https:\/\/www.quebakan.com\/v15\/#organization"},"image":{"@id":"https:\/\/www.quebakan.com\/v15\/el-poker-es-el-nuevo-deporte-mental\/#primaryimage"},"thumbnailUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/05\/64febdcc-7ec8-4baf-a499-ffde7fee9baf.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.quebakan.com\/v15\/el-poker-es-el-nuevo-deporte-mental\/","url":"https:\/\/www.quebakan.com\/v15\/el-poker-es-el-nuevo-deporte-mental\/","name":"EL POKER ES EL NUEVO DEPORTE MENTAL &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","isPartOf":{"@id":"https:\/\/www.quebakan.com\/v15\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.quebakan.com\/v15\/el-poker-es-el-nuevo-deporte-mental\/#primaryimage"},"image":{"@id":"https:\/\/www.quebakan.com\/v15\/el-poker-es-el-nuevo-deporte-mental\/#primaryimage"},"thumbnailUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/05\/64febdcc-7ec8-4baf-a499-ffde7fee9baf.jpg","datePublished":"2024-05-19T05:17:57+00:00","breadcrumb":{"@id":"https:\/\/www.quebakan.com\/v15\/el-poker-es-el-nuevo-deporte-mental\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.quebakan.com\/v15\/el-poker-es-el-nuevo-deporte-mental\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.quebakan.com\/v15\/el-poker-es-el-nuevo-deporte-mental\/#primaryimage","url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/05\/64febdcc-7ec8-4baf-a499-ffde7fee9baf.jpg","contentUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/05\/64febdcc-7ec8-4baf-a499-ffde7fee9baf.jpg","width":700,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/www.quebakan.com\/v15\/el-poker-es-el-nuevo-deporte-mental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.quebakan.com\/v15\/"},{"@type":"ListItem","position":2,"name":"EL POKER ES EL NUEVO DEPORTE MENTAL"}]},{"@type":"WebSite","@id":"https:\/\/www.quebakan.com\/v15\/#website","url":"https:\/\/www.quebakan.com\/v15\/","name":"QUEBAKAN","description":"..","publisher":{"@id":"https:\/\/www.quebakan.com\/v15\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.quebakan.com\/v15\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.quebakan.com\/v15\/#organization","name":"Quebakan.com","url":"https:\/\/www.quebakan.com\/v15\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/logo\/image\/","url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/logoquebakanenero2021.jpg","contentUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/logoquebakanenero2021.jpg","width":1920,"height":1080,"caption":"Quebakan.com"},"image":{"@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/quebakan","https:\/\/x.com\/quebakanec","http:\/\/www.instagram.com\/quebakan","http:\/\/www.youtube.com\/quebakan1"]},{"@type":"Person","@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/person\/d90fa9f9cfa81eb8ace9811e5b7b9118","name":"Erick Villafuerte","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/avatars\/4\/1731297654-bpfull.png","url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/avatars\/4\/1731297654-bpfull.png","contentUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/avatars\/4\/1731297654-bpfull.png","caption":"Erick Villafuerte"}}]}},"_links":{"self":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts\/119159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/comments?post=119159"}],"version-history":[{"count":1,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts\/119159\/revisions"}],"predecessor-version":[{"id":119163,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts\/119159\/revisions\/119163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/media\/119161"}],"wp:attachment":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/media?parent=119159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/categories?post=119159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/tags?post=119159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}