{"id":120050,"date":"2024-06-09T21:10:10","date_gmt":"2024-06-10T02:10:10","guid":{"rendered":"https:\/\/www.quebakan.com\/v15\/?p=120050"},"modified":"2024-06-09T21:10:10","modified_gmt":"2024-06-10T02:10:10","slug":"pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil","status":"publish","type":"post","link":"https:\/\/www.quebakan.com\/v15\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\/","title":{"rendered":"PedidosYa se convierte en la primera plataforma externa de delivery para T\u00cdA en Guayaquil"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-120051\" src=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/06\/240529_Foto_BP_AlianzaTia_PedidosYa.jpg\" alt=\"\" width=\"700\" height=\"394\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><em><strong>Pie de foto:<\/strong> Carla Paladines &#8211; Gerente de Medios Digitales T\u00eda, Paolo Novasco &#8211; Head de Quick Commerce PedidosYa, Fernando Alvarado &#8211; Gerente Regional de Operaciones T\u00eda, Arley Tomal\u00e1 &#8211; Trabajador Operativo T\u00eda, Sof\u00eda Retamales &#8211; Gerente de Datos Maestros y Alianzas Quick Commerce T\u00eda.<\/em><\/span><\/p>\n<ul style=\"text-align: justify;\">\n<li><span style=\"color: #000000;\"><em>PedidosYa es el \u00fanico canal digital externo a las operaciones de la cadena de supermercados T\u00eda.<\/em><\/span><\/li>\n<li><span style=\"color: #000000;\"><em>Al momento T\u00eda estar\u00e1 presente en la app para los clientes en Guayaquil. <\/em><\/span><\/li>\n<li><span style=\"color: #000000;\"><em>Se estima expandir su presencia a las 15 ciudades donde PedidosYa tiene operaci\u00f3n en los pr\u00f3ximos meses.<br \/>\n<\/em><\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Guayaquil, mayo de 2024 &#8211; PedidosYa, la plataforma l\u00edder de delivery a nivel nacional, incorpora a su vertical de supermercados a T\u00cdA, la cadena de almacenes con mayor cobertura en el pa\u00eds. <\/strong>Esta nueva apuesta busca ampliar la variedad que ofrece actualmente la app a sus clientes, por lo que T\u00eda llegar\u00e1 con m\u00e1s de 6 mil \u00edtems, que incluir\u00e1 su portafolio de marcas propias, nacionales e importadas. De esta manera, PedidosYa se convierte en la primera plataforma externa de delivery donde T\u00eda est\u00e1 presente.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Inicialmente, los productos de T\u00eda estar\u00e1n disponibles para los clientes de Guayaquil. Sin embargo, PedidosYa inform\u00f3 que busca su expansi\u00f3n a las 15 ciudades donde la app est\u00e1 presente. <em>\u201cSomos la aplicaci\u00f3n n\u00famero uno de delivery del pa\u00eds, adem\u00e1s la marca de mayor recordaci\u00f3n en cuanto a delivery de supermercados, por lo que esta alianza refuerza el compromiso de mejorar la atenci\u00f3n a nuestros clientes. Las dos marcas tenemos como prioridad brindar a nuestros clientes la mejor experiencia para hacer sus compras de supermercado sin salir de casa\u201d,<\/em> se\u00f1al\u00f3 Paolo Novasco, Head de Quick Commerce de PedidosYa.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El tiempo promedio de entrega de productos de T\u00eda ser\u00e1 de aproximadamente 40 minutos. Adem\u00e1s, la empresa asegura que brindar\u00e1 las mismas ofertas y promociones de sus tiendas f\u00edsicas en la plataforma. Tambi\u00e9n, se ver\u00e1n reflejadas promociones exclusivas en las principales categor\u00edas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La categor\u00eda de supermercados de PedidosYa ha tenido un crecimiento de 55% el \u00faltimo a\u00f1o y cuenta actualmente con m\u00e1s de 100 aliados comerciales para brindar una nueva experiencia al cliente de hacer sus compras de supermercados y conveniencia en la app sin salir de casa.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Es as\u00ed como PedidosYa contin\u00faa fortaleciendo su oferta de valor, reiterando su compromiso de seguir brindando m\u00faltiples beneficios para sus usuarios, entre los cuales destacan el poder realizar sus pedidos desde la comodidad de sus casas, ahorrando tiempo y evitando filas; acceder a descuentos especiales y promociones exclusivas; y, por supuesto, la garant\u00eda de un servicio oportuno y eficiente.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pie de foto: Carla Paladines &#8211; Gerente de Medios Digitales T\u00eda, Paolo Novasco &#8211; Head de Quick Commerce PedidosYa, Fernando Alvarado &#8211; Gerente Regional de Operaciones T\u00eda, Arley Tomal\u00e1 &#8211; Trabajador Operativo T\u00eda, Sof\u00eda Retamales &#8211; Gerente de Datos Maestros y Alianzas Quick Commerce T\u00eda. PedidosYa es el \u00fanico canal digital externo a las operaciones [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":120051,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"buzzeditor_post_format":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-120050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PedidosYa se convierte en la primera plataforma externa de delivery para T\u00cdA en Guayaquil &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.quebakan.com\/v15\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PedidosYa se convierte en la primera plataforma externa de delivery para T\u00cdA en Guayaquil &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....\" \/>\n<meta property=\"og:description\" content=\"Pie de foto: Carla Paladines &#8211; Gerente de Medios Digitales T\u00eda, Paolo Novasco &#8211; Head de Quick Commerce PedidosYa, Fernando Alvarado &#8211; Gerente Regional de Operaciones T\u00eda, Arley Tomal\u00e1 &#8211; Trabajador Operativo T\u00eda, Sof\u00eda Retamales &#8211; Gerente de Datos Maestros y Alianzas Quick Commerce T\u00eda. PedidosYa es el \u00fanico canal digital externo a las operaciones [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.quebakan.com\/v15\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\/\" \/>\n<meta property=\"og:site_name\" content=\"QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/quebakan\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-10T02:10:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/06\/240529_Foto_BP_AlianzaTia_PedidosYa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erick Villafuerte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@quebakanec\" \/>\n<meta name=\"twitter:site\" content=\"@quebakanec\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erick Villafuerte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\\\/\"},\"author\":{\"name\":\"Erick Villafuerte\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/person\\\/d90fa9f9cfa81eb8ace9811e5b7b9118\"},\"headline\":\"PedidosYa se convierte en la primera plataforma externa de delivery para T\u00cdA en Guayaquil\",\"datePublished\":\"2024-06-10T02:10:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\\\/\"},\"wordCount\":465,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/240529_Foto_BP_AlianzaTia_PedidosYa.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\\\/\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\\\/\",\"name\":\"PedidosYa se convierte en la primera plataforma externa de delivery para T\u00cdA en Guayaquil &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/240529_Foto_BP_AlianzaTia_PedidosYa.jpg\",\"datePublished\":\"2024-06-10T02:10:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/240529_Foto_BP_AlianzaTia_PedidosYa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/240529_Foto_BP_AlianzaTia_PedidosYa.jpg\",\"width\":700,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PedidosYa se convierte en la primera plataforma externa de delivery para T\u00cdA en Guayaquil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#website\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/\",\"name\":\"QUEBAKAN\",\"description\":\"..\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#organization\",\"name\":\"Quebakan.com\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logoquebakanenero2021.jpg\",\"contentUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logoquebakanenero2021.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Quebakan.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/quebakan\",\"https:\\\/\\\/x.com\\\/quebakanec\",\"http:\\\/\\\/www.instagram.com\\\/quebakan\",\"http:\\\/\\\/www.youtube.com\\\/quebakan1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/person\\\/d90fa9f9cfa81eb8ace9811e5b7b9118\",\"name\":\"Erick Villafuerte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/avatars\\\/4\\\/1731297654-bpfull.png\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/avatars\\\/4\\\/1731297654-bpfull.png\",\"contentUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/avatars\\\/4\\\/1731297654-bpfull.png\",\"caption\":\"Erick Villafuerte\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PedidosYa se convierte en la primera plataforma externa de delivery para T\u00cdA en Guayaquil &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.quebakan.com\/v15\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\/","og_locale":"es_ES","og_type":"article","og_title":"PedidosYa se convierte en la primera plataforma externa de delivery para T\u00cdA en Guayaquil &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","og_description":"Pie de foto: Carla Paladines &#8211; Gerente de Medios Digitales T\u00eda, Paolo Novasco &#8211; Head de Quick Commerce PedidosYa, Fernando Alvarado &#8211; Gerente Regional de Operaciones T\u00eda, Arley Tomal\u00e1 &#8211; Trabajador Operativo T\u00eda, Sof\u00eda Retamales &#8211; Gerente de Datos Maestros y Alianzas Quick Commerce T\u00eda. PedidosYa es el \u00fanico canal digital externo a las operaciones [&hellip;]","og_url":"https:\/\/www.quebakan.com\/v15\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\/","og_site_name":"QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","article_publisher":"http:\/\/www.facebook.com\/quebakan","article_published_time":"2024-06-10T02:10:10+00:00","og_image":[{"width":700,"height":394,"url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/06\/240529_Foto_BP_AlianzaTia_PedidosYa.jpg","type":"image\/jpeg"}],"author":"Erick Villafuerte","twitter_card":"summary_large_image","twitter_creator":"@quebakanec","twitter_site":"@quebakanec","twitter_misc":{"Escrito por":"Erick Villafuerte","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.quebakan.com\/v15\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\/#article","isPartOf":{"@id":"https:\/\/www.quebakan.com\/v15\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\/"},"author":{"name":"Erick Villafuerte","@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/person\/d90fa9f9cfa81eb8ace9811e5b7b9118"},"headline":"PedidosYa se convierte en la primera plataforma externa de delivery para T\u00cdA en Guayaquil","datePublished":"2024-06-10T02:10:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.quebakan.com\/v15\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\/"},"wordCount":465,"commentCount":0,"publisher":{"@id":"https:\/\/www.quebakan.com\/v15\/#organization"},"image":{"@id":"https:\/\/www.quebakan.com\/v15\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/06\/240529_Foto_BP_AlianzaTia_PedidosYa.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.quebakan.com\/v15\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\/","url":"https:\/\/www.quebakan.com\/v15\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\/","name":"PedidosYa se convierte en la primera plataforma externa de delivery para T\u00cdA en Guayaquil &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","isPartOf":{"@id":"https:\/\/www.quebakan.com\/v15\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.quebakan.com\/v15\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\/#primaryimage"},"image":{"@id":"https:\/\/www.quebakan.com\/v15\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/06\/240529_Foto_BP_AlianzaTia_PedidosYa.jpg","datePublished":"2024-06-10T02:10:10+00:00","breadcrumb":{"@id":"https:\/\/www.quebakan.com\/v15\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.quebakan.com\/v15\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.quebakan.com\/v15\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\/#primaryimage","url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/06\/240529_Foto_BP_AlianzaTia_PedidosYa.jpg","contentUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2024\/06\/240529_Foto_BP_AlianzaTia_PedidosYa.jpg","width":700,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/www.quebakan.com\/v15\/pedidosya-se-convierte-en-la-primera-plataforma-externa-de-delivery-para-tia-en-guayaquil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.quebakan.com\/v15\/"},{"@type":"ListItem","position":2,"name":"PedidosYa se convierte en la primera plataforma externa de delivery para T\u00cdA en Guayaquil"}]},{"@type":"WebSite","@id":"https:\/\/www.quebakan.com\/v15\/#website","url":"https:\/\/www.quebakan.com\/v15\/","name":"QUEBAKAN","description":"..","publisher":{"@id":"https:\/\/www.quebakan.com\/v15\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.quebakan.com\/v15\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.quebakan.com\/v15\/#organization","name":"Quebakan.com","url":"https:\/\/www.quebakan.com\/v15\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/logo\/image\/","url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/logoquebakanenero2021.jpg","contentUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/logoquebakanenero2021.jpg","width":1920,"height":1080,"caption":"Quebakan.com"},"image":{"@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/quebakan","https:\/\/x.com\/quebakanec","http:\/\/www.instagram.com\/quebakan","http:\/\/www.youtube.com\/quebakan1"]},{"@type":"Person","@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/person\/d90fa9f9cfa81eb8ace9811e5b7b9118","name":"Erick Villafuerte","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/avatars\/4\/1731297654-bpfull.png","url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/avatars\/4\/1731297654-bpfull.png","contentUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/avatars\/4\/1731297654-bpfull.png","caption":"Erick Villafuerte"}}]}},"_links":{"self":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts\/120050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/comments?post=120050"}],"version-history":[{"count":1,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts\/120050\/revisions"}],"predecessor-version":[{"id":120052,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts\/120050\/revisions\/120052"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/media\/120051"}],"wp:attachment":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/media?parent=120050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/categories?post=120050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/tags?post=120050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}