{"id":144610,"date":"2026-07-14T16:34:24","date_gmt":"2026-07-14T21:34:24","guid":{"rendered":"https:\/\/www.quebakan.com\/v15\/?p=144610"},"modified":"2026-07-14T16:34:24","modified_gmt":"2026-07-14T21:34:24","slug":"mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos","status":"publish","type":"post","link":"https:\/\/www.quebakan.com\/v15\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\/","title":{"rendered":"Mall del Sur impulsa el comercio por las fiestas de la ciudad con descuentos y sorteos en \u201cSaldos Julianos\u201d"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-144611\" src=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2026\/07\/SALDOS-JULIANOS.jpg\" alt=\"\" width=\"495\" height=\"700\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Con motivo de las festividades por la Fundaci\u00f3n de Guayaquil, <strong>Mall del Sur<\/strong> presenta una nueva edici\u00f3n de su campa\u00f1a <strong>\u00abSaldos Julianos\u00bb<\/strong>, una iniciativa que busca dinamizar la actividad comercial ofreciendo importantes descuentos y beneficios para quienes realicen sus compras durante esta temporada.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Del <strong>14 al 19 de julio<\/strong>, los visitantes podr\u00e1n acceder a descuentos de hasta el <strong>70%<\/strong> en una amplia variedad de productos y servicios de los locales participantes, consolidando al centro comercial como uno de los principales puntos de compra durante las celebraciones julianas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Como parte de la campa\u00f1a, Mall del Sur tambi\u00e9n premiar\u00e1 la preferencia de sus clientes. Por cada <strong>$30 en compras<\/strong> (facturas acumulables), los participantes podr\u00e1n registrarse para el <strong>sorteo de tres Smart TV de 55 pulgadas<\/strong>, incentivo que complementa esta temporada de promociones y fomenta una mayor actividad comercial entre las diferentes categor\u00edas del centro comercial.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Con esta propuesta, Mall del Sur se suma a la agenda de actividades que acompa\u00f1an la celebraci\u00f3n de la ciudad, promoviendo espacios donde los consumidores pueden acceder a ofertas especiales mientras apoyan al comercio local y disfrutan de una experiencia integral de compras.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Para conocer los locales participantes, condiciones de la promoci\u00f3n y pr\u00f3ximas actividades, los interesados pueden visitar las redes sociales oficiales de <strong>Mall del Sur<\/strong>: <strong>@malldelsur<\/strong>.<\/span><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-144612\" src=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2026\/07\/Foto-1-2.jpg\" alt=\"\" width=\"700\" height=\"359\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-144613\" src=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2026\/07\/Foto-2-1.jpg\" alt=\"\" width=\"700\" height=\"371\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-144614\" src=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2026\/07\/Foto-3-1.jpg\" alt=\"\" width=\"700\" height=\"359\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con motivo de las festividades por la Fundaci\u00f3n de Guayaquil, Mall del Sur presenta una nueva edici\u00f3n de su campa\u00f1a \u00abSaldos Julianos\u00bb, una iniciativa que busca dinamizar la actividad comercial ofreciendo importantes descuentos y beneficios para quienes realicen sus compras durante esta temporada. Del 14 al 19 de julio, los visitantes podr\u00e1n acceder a descuentos [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":144611,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"buzzeditor_post_format":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-144610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mall del Sur impulsa el comercio por las fiestas de la ciudad con descuentos y sorteos en \u201cSaldos Julianos\u201d &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.quebakan.com\/v15\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mall del Sur impulsa el comercio por las fiestas de la ciudad con descuentos y sorteos en \u201cSaldos Julianos\u201d &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....\" \/>\n<meta property=\"og:description\" content=\"Con motivo de las festividades por la Fundaci\u00f3n de Guayaquil, Mall del Sur presenta una nueva edici\u00f3n de su campa\u00f1a \u00abSaldos Julianos\u00bb, una iniciativa que busca dinamizar la actividad comercial ofreciendo importantes descuentos y beneficios para quienes realicen sus compras durante esta temporada. Del 14 al 19 de julio, los visitantes podr\u00e1n acceder a descuentos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.quebakan.com\/v15\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\/\" \/>\n<meta property=\"og:site_name\" content=\"QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/quebakan\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T21:34:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2026\/07\/SALDOS-JULIANOS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"495\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erick Villafuerte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@quebakanec\" \/>\n<meta name=\"twitter:site\" content=\"@quebakanec\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erick Villafuerte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\\\/\"},\"author\":{\"name\":\"Erick Villafuerte\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/person\\\/d90fa9f9cfa81eb8ace9811e5b7b9118\"},\"headline\":\"Mall del Sur impulsa el comercio por las fiestas de la ciudad con descuentos y sorteos en \u201cSaldos Julianos\u201d\",\"datePublished\":\"2026-07-14T21:34:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\\\/\"},\"wordCount\":239,\"publisher\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/SALDOS-JULIANOS.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\\\/\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\\\/\",\"name\":\"Mall del Sur impulsa el comercio por las fiestas de la ciudad con descuentos y sorteos en \u201cSaldos Julianos\u201d &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/SALDOS-JULIANOS.jpg\",\"datePublished\":\"2026-07-14T21:34:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/SALDOS-JULIANOS.jpg\",\"contentUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/SALDOS-JULIANOS.jpg\",\"width\":495,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mall del Sur impulsa el comercio por las fiestas de la ciudad con descuentos y sorteos en \u201cSaldos Julianos\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#website\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/\",\"name\":\"QUEBAKAN\",\"description\":\"..\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#organization\",\"name\":\"Quebakan.com\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logoquebakanenero2021.jpg\",\"contentUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logoquebakanenero2021.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Quebakan.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/quebakan\",\"https:\\\/\\\/x.com\\\/quebakanec\",\"http:\\\/\\\/www.instagram.com\\\/quebakan\",\"http:\\\/\\\/www.youtube.com\\\/quebakan1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/#\\\/schema\\\/person\\\/d90fa9f9cfa81eb8ace9811e5b7b9118\",\"name\":\"Erick Villafuerte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/avatars\\\/4\\\/1731297654-bpfull.png\",\"url\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/avatars\\\/4\\\/1731297654-bpfull.png\",\"contentUrl\":\"https:\\\/\\\/www.quebakan.com\\\/v15\\\/wp-content\\\/uploads\\\/avatars\\\/4\\\/1731297654-bpfull.png\",\"caption\":\"Erick Villafuerte\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mall del Sur impulsa el comercio por las fiestas de la ciudad con descuentos y sorteos en \u201cSaldos Julianos\u201d &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.quebakan.com\/v15\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\/","og_locale":"es_ES","og_type":"article","og_title":"Mall del Sur impulsa el comercio por las fiestas de la ciudad con descuentos y sorteos en \u201cSaldos Julianos\u201d &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","og_description":"Con motivo de las festividades por la Fundaci\u00f3n de Guayaquil, Mall del Sur presenta una nueva edici\u00f3n de su campa\u00f1a \u00abSaldos Julianos\u00bb, una iniciativa que busca dinamizar la actividad comercial ofreciendo importantes descuentos y beneficios para quienes realicen sus compras durante esta temporada. Del 14 al 19 de julio, los visitantes podr\u00e1n acceder a descuentos [&hellip;]","og_url":"https:\/\/www.quebakan.com\/v15\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\/","og_site_name":"QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","article_publisher":"http:\/\/www.facebook.com\/quebakan","article_published_time":"2026-07-14T21:34:24+00:00","og_image":[{"width":495,"height":700,"url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2026\/07\/SALDOS-JULIANOS.jpg","type":"image\/jpeg"}],"author":"Erick Villafuerte","twitter_card":"summary_large_image","twitter_creator":"@quebakanec","twitter_site":"@quebakanec","twitter_misc":{"Escrito por":"Erick Villafuerte","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.quebakan.com\/v15\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\/#article","isPartOf":{"@id":"https:\/\/www.quebakan.com\/v15\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\/"},"author":{"name":"Erick Villafuerte","@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/person\/d90fa9f9cfa81eb8ace9811e5b7b9118"},"headline":"Mall del Sur impulsa el comercio por las fiestas de la ciudad con descuentos y sorteos en \u201cSaldos Julianos\u201d","datePublished":"2026-07-14T21:34:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.quebakan.com\/v15\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\/"},"wordCount":239,"publisher":{"@id":"https:\/\/www.quebakan.com\/v15\/#organization"},"image":{"@id":"https:\/\/www.quebakan.com\/v15\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2026\/07\/SALDOS-JULIANOS.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.quebakan.com\/v15\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\/","url":"https:\/\/www.quebakan.com\/v15\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\/","name":"Mall del Sur impulsa el comercio por las fiestas de la ciudad con descuentos y sorteos en \u201cSaldos Julianos\u201d &#8211; QUEBAKAN.COM 2026: Noticias, Eventos, Conciertos y mucho m\u00e1s....","isPartOf":{"@id":"https:\/\/www.quebakan.com\/v15\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.quebakan.com\/v15\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\/#primaryimage"},"image":{"@id":"https:\/\/www.quebakan.com\/v15\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2026\/07\/SALDOS-JULIANOS.jpg","datePublished":"2026-07-14T21:34:24+00:00","breadcrumb":{"@id":"https:\/\/www.quebakan.com\/v15\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.quebakan.com\/v15\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.quebakan.com\/v15\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\/#primaryimage","url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2026\/07\/SALDOS-JULIANOS.jpg","contentUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2026\/07\/SALDOS-JULIANOS.jpg","width":495,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/www.quebakan.com\/v15\/mall-del-sur-impulsa-el-comercio-por-las-fiestas-de-la-ciudad-con-descuentos-y-sorteos-en-saldos-julianos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.quebakan.com\/v15\/"},{"@type":"ListItem","position":2,"name":"Mall del Sur impulsa el comercio por las fiestas de la ciudad con descuentos y sorteos en \u201cSaldos Julianos\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.quebakan.com\/v15\/#website","url":"https:\/\/www.quebakan.com\/v15\/","name":"QUEBAKAN","description":"..","publisher":{"@id":"https:\/\/www.quebakan.com\/v15\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.quebakan.com\/v15\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.quebakan.com\/v15\/#organization","name":"Quebakan.com","url":"https:\/\/www.quebakan.com\/v15\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/logo\/image\/","url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/logoquebakanenero2021.jpg","contentUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/2023\/07\/logoquebakanenero2021.jpg","width":1920,"height":1080,"caption":"Quebakan.com"},"image":{"@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/quebakan","https:\/\/x.com\/quebakanec","http:\/\/www.instagram.com\/quebakan","http:\/\/www.youtube.com\/quebakan1"]},{"@type":"Person","@id":"https:\/\/www.quebakan.com\/v15\/#\/schema\/person\/d90fa9f9cfa81eb8ace9811e5b7b9118","name":"Erick Villafuerte","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/avatars\/4\/1731297654-bpfull.png","url":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/avatars\/4\/1731297654-bpfull.png","contentUrl":"https:\/\/www.quebakan.com\/v15\/wp-content\/uploads\/avatars\/4\/1731297654-bpfull.png","caption":"Erick Villafuerte"}}]}},"_links":{"self":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts\/144610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/comments?post=144610"}],"version-history":[{"count":1,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts\/144610\/revisions"}],"predecessor-version":[{"id":144615,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/posts\/144610\/revisions\/144615"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/media\/144611"}],"wp:attachment":[{"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/media?parent=144610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/categories?post=144610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.quebakan.com\/v15\/wp-json\/wp\/v2\/tags?post=144610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}